{"id":104355,"date":"2020-06-03T22:52:39","date_gmt":"2020-06-04T02:52:39","guid":{"rendered":"https:\/\/digital58.com.ve\/site\/?p=104355"},"modified":"2020-06-03T22:52:39","modified_gmt":"2020-06-04T02:52:39","slug":"el-mensaje-de-coquito-sobre-el-racismo-en-venezuela","status":"publish","type":"post","link":"https:\/\/digital58.com.ve\/site\/2020\/06\/03\/el-mensaje-de-coquito-sobre-el-racismo-en-venezuela\/","title":{"rendered":"El mensaje de Coquito sobre el racismo en Venezuela"},"content":{"rendered":"\r\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2020\/06\/coquito.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-104421\" src=\"https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2020\/06\/coquito.jpg\" alt=\"\" width=\"607\" height=\"338\" srcset=\"https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2020\/06\/coquito.jpg 607w, https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2020\/06\/coquito-300x167.jpg 300w\" sizes=\"auto, (max-width: 607px) 100vw, 607px\" \/><\/a><\/p><div class=\"ksjri6a57850370a9d\" ><p style=\"text-align: center;\"><a href=\"https:\/\/t.me\/noticiasdigital58\" target=\"_blank\" rel=\"noopener\"><img class=\"aligncenter size-full wp-image-125363\" src=\"https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2021\/04\/banner-telegram-web-2021.png\" alt=\"\" width=\"600\" height=\"90\" \/><\/a><\/p><\/div><style type=\"text\/css\">\r\n@media screen and (min-width: 1201px) {\r\n.ksjri6a57850370a9d {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.ksjri6a57850370a9d {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.ksjri6a57850370a9d {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.ksjri6a57850370a9d {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.ksjri6a57850370a9d {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n\r\n<p>El actor venezolano Wilmer Machado, conocido como \u00abCoquito\u00bb, public\u00f3 un mensaje en su red social Instagram sobre el racismo, el criollo afirm\u00f3 sentirse orgulloso por su color de piel y aseguro que el respeto es la mejor soluci\u00f3n para todo en la vida. Coquito realiz\u00f3 esta publicaci\u00f3n como consecuencia a la oleada de protestas en todo el mundo por el racismo, tras la muerte de George Floyd.<br \/><br \/><strong>Caracas, Venezuela 3 de junio de 2020 (ND58).-<\/strong> El actor venezolano Wilmer Machado reconocido por el nombre art\u00edstico de \u00abCoquito,\u00bb no tard\u00f3 mucho en pronunciarse contra el racismo, el actor le atribuy\u00f3 a su color de piel lo que le dio la oportunidad de llegar al campo actoral y poder brillar, agrego que pudo comer y vivir del arte gracias a su color de piel moreno.<br \/><br \/>\u00abEntre mis m\u00e1s grandes pertenencias, esta mi color de piel. Que considero maravilloso y hermoso. Fue la condici\u00f3n indispensable para mi primer trabajo profesional\u00bb, dijo \u00abCoquito\u00bb.<br \/><br \/>Tambi\u00e9n el actor venezolano cit\u00f3 a grandes int\u00e9rpretes de la historia universal sobre el significado de la palabra \u00abNegro\u00bb la cual es bastante normal en el dialecto venezolano, hasta para dirigirse a alguien con cari\u00f1o, aunque en muchas palabras sea mal vista hasta el modo que no la puedes pronunciar en voz alta. <br \/><br \/>El actor, cit\u00f3 a grandes pensadores de la historia universal sobre la palabra \u00abNegro\u00bb, que en muchos lugares puede ser visto como una ofensa, y precis\u00f3 que esto nunca le har\u00e1 sentirse mal.<br \/><br \/>\u00abYo lo digo desde lo m\u00e1s profundo de mi ser: No me llames moreno, no me llames noche, no me llames de color, ll\u00e1mame NEGRO. Te aseguro que volteare con una sonrisa y con el pecho inflado. Jam\u00e1s lograras hacerme sentir ofendido quien desde el insulto utilice ese t\u00e9rmino para referirse a mi, es mi verdad y a diario el espejo me la recuerda y yo le devuelvo el favor convertido en el suspiro de un hombre pleno y lleno de orgullo\u00bb, concluy\u00f3 Conquito<br \/><br \/><strong>Redacci\u00f3n: Rubio, Laura Isabel (@lauraisabelrubio) | Fuente: Agencias <\/strong><br \/><strong>Edici\u00f3n: Villasmil, Henry<\/strong><br \/><strong>Gr\u00e1ficas: Cortes\u00eda<\/strong><br \/><br \/><\/p>\r\n<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div>","protected":false},"excerpt":{"rendered":"<p>El actor venezolano Wilmer Machado, conocido como \u00abCoquito\u00bb, public\u00f3 un mensaje en su red social Instagram sobre el racismo, el<\/p>\n","protected":false},"author":28,"featured_media":104421,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_uag_custom_page_level_css":"","footnotes":""},"categories":[1],"tags":[1843,29,15452,50,273,15201,233,7431,32,15451],"class_list":["post-104355","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fama","tag-actores","tag-caracas","tag-coquito","tag-entretenimiento","tag-farandula","tag-george-floyd","tag-nacionales","tag-racismo","tag-venezuela","tag-wilmer-machado"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El mensaje de Coquito sobre el racismo en Venezuela<\/title>\n<meta name=\"description\" content=\"Fama\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/digital58.com.ve\/site\/2020\/06\/03\/el-mensaje-de-coquito-sobre-el-racismo-en-venezuela\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El mensaje de Coquito sobre el racismo en Venezuela\" \/>\n<meta property=\"og:description\" content=\"Fama\" \/>\n<meta property=\"og:url\" content=\"https:\/\/digital58.com.ve\/site\/2020\/06\/03\/el-mensaje-de-coquito-sobre-el-racismo-en-venezuela\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Digital58\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-04T02:52:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2020\/06\/coquito.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"607\" \/>\n\t<meta property=\"og:image:height\" content=\"338\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rubio Laura Isabel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Digital_58\" \/>\n<meta name=\"twitter:site\" content=\"@villasmilhfoto\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rubio Laura Isabel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/2020\\\/06\\\/03\\\/el-mensaje-de-coquito-sobre-el-racismo-en-venezuela\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/2020\\\/06\\\/03\\\/el-mensaje-de-coquito-sobre-el-racismo-en-venezuela\\\/\"},\"author\":{\"name\":\"Rubio Laura Isabel\",\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/#\\\/schema\\\/person\\\/6672bab44ab958838204ebb2cb0e8d52\"},\"headline\":\"El mensaje de Coquito sobre el racismo en Venezuela\",\"datePublished\":\"2020-06-04T02:52:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/2020\\\/06\\\/03\\\/el-mensaje-de-coquito-sobre-el-racismo-en-venezuela\\\/\"},\"wordCount\":365,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/#\\\/schema\\\/person\\\/64d1c2e4d0d4fd1b849980c4331c2951\"},\"image\":{\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/2020\\\/06\\\/03\\\/el-mensaje-de-coquito-sobre-el-racismo-en-venezuela\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/coquito.jpg\",\"keywords\":[\"Actores\",\"Caracas\",\"Coquito\",\"Entretenimiento\",\"Far\u00e1ndula\",\"George Floyd\",\"Nacionales\",\"Racismo\",\"Venezuela\",\"Wilmer Machado\"],\"articleSection\":[\"Fama\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/digital58.com.ve\\\/site\\\/2020\\\/06\\\/03\\\/el-mensaje-de-coquito-sobre-el-racismo-en-venezuela\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/2020\\\/06\\\/03\\\/el-mensaje-de-coquito-sobre-el-racismo-en-venezuela\\\/\",\"url\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/2020\\\/06\\\/03\\\/el-mensaje-de-coquito-sobre-el-racismo-en-venezuela\\\/\",\"name\":\"El mensaje de Coquito sobre el racismo en Venezuela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/2020\\\/06\\\/03\\\/el-mensaje-de-coquito-sobre-el-racismo-en-venezuela\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/2020\\\/06\\\/03\\\/el-mensaje-de-coquito-sobre-el-racismo-en-venezuela\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/coquito.jpg\",\"datePublished\":\"2020-06-04T02:52:39+00:00\",\"description\":\"Fama\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/2020\\\/06\\\/03\\\/el-mensaje-de-coquito-sobre-el-racismo-en-venezuela\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/digital58.com.ve\\\/site\\\/2020\\\/06\\\/03\\\/el-mensaje-de-coquito-sobre-el-racismo-en-venezuela\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/2020\\\/06\\\/03\\\/el-mensaje-de-coquito-sobre-el-racismo-en-venezuela\\\/#primaryimage\",\"url\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/coquito.jpg\",\"contentUrl\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/coquito.jpg\",\"width\":607,\"height\":338},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/2020\\\/06\\\/03\\\/el-mensaje-de-coquito-sobre-el-racismo-en-venezuela\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El mensaje de Coquito sobre el racismo en Venezuela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/\",\"name\":\"Noticias Digital58\",\"description\":\"Portal de Noticias \u00a1Periodismo web de verdad! Lanzamiento web 22.11.2005 \\\/ Maracaibo, Venezuela\",\"publisher\":{\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/#\\\/schema\\\/person\\\/64d1c2e4d0d4fd1b849980c4331c2951\"},\"alternateName\":\"ND58\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/#\\\/schema\\\/person\\\/64d1c2e4d0d4fd1b849980c4331c2951\",\"name\":\"Villasmil Henry\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb0c4a2fcb7970138239f7e404ea75757b1b507b28b5ce4c53fbd62d797c5a7c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb0c4a2fcb7970138239f7e404ea75757b1b507b28b5ce4c53fbd62d797c5a7c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb0c4a2fcb7970138239f7e404ea75757b1b507b28b5ce4c53fbd62d797c5a7c?s=96&d=mm&r=g\",\"caption\":\"Villasmil Henry\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb0c4a2fcb7970138239f7e404ea75757b1b507b28b5ce4c53fbd62d797c5a7c?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/www.henryvillasmil.com.ve\",\"https:\\\/\\\/www.instagram.com\\\/villasmilhfoto\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/villasmilhfoto\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/#\\\/schema\\\/person\\\/6672bab44ab958838204ebb2cb0e8d52\",\"name\":\"Rubio Laura Isabel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f7cc56b26fb0562df4488ff129a58c3c1a1bd264c9af5f313a9b1797fff1cfb9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f7cc56b26fb0562df4488ff129a58c3c1a1bd264c9af5f313a9b1797fff1cfb9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f7cc56b26fb0562df4488ff129a58c3c1a1bd264c9af5f313a9b1797fff1cfb9?s=96&d=mm&r=g\",\"caption\":\"Rubio Laura Isabel\"},\"url\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/author\\\/laurarubio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El mensaje de Coquito sobre el racismo en Venezuela","description":"Fama","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/digital58.com.ve\/site\/2020\/06\/03\/el-mensaje-de-coquito-sobre-el-racismo-en-venezuela\/","og_locale":"es_ES","og_type":"article","og_title":"El mensaje de Coquito sobre el racismo en Venezuela","og_description":"Fama","og_url":"https:\/\/digital58.com.ve\/site\/2020\/06\/03\/el-mensaje-de-coquito-sobre-el-racismo-en-venezuela\/","og_site_name":"Noticias Digital58","article_published_time":"2020-06-04T02:52:39+00:00","og_image":[{"width":607,"height":338,"url":"https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2020\/06\/coquito.jpg","type":"image\/jpeg"}],"author":"Rubio Laura Isabel","twitter_card":"summary_large_image","twitter_creator":"@Digital_58","twitter_site":"@villasmilhfoto","twitter_misc":{"Escrito por":"Rubio Laura Isabel","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/digital58.com.ve\/site\/2020\/06\/03\/el-mensaje-de-coquito-sobre-el-racismo-en-venezuela\/#article","isPartOf":{"@id":"https:\/\/digital58.com.ve\/site\/2020\/06\/03\/el-mensaje-de-coquito-sobre-el-racismo-en-venezuela\/"},"author":{"name":"Rubio Laura Isabel","@id":"https:\/\/digital58.com.ve\/site\/#\/schema\/person\/6672bab44ab958838204ebb2cb0e8d52"},"headline":"El mensaje de Coquito sobre el racismo en Venezuela","datePublished":"2020-06-04T02:52:39+00:00","mainEntityOfPage":{"@id":"https:\/\/digital58.com.ve\/site\/2020\/06\/03\/el-mensaje-de-coquito-sobre-el-racismo-en-venezuela\/"},"wordCount":365,"commentCount":0,"publisher":{"@id":"https:\/\/digital58.com.ve\/site\/#\/schema\/person\/64d1c2e4d0d4fd1b849980c4331c2951"},"image":{"@id":"https:\/\/digital58.com.ve\/site\/2020\/06\/03\/el-mensaje-de-coquito-sobre-el-racismo-en-venezuela\/#primaryimage"},"thumbnailUrl":"https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2020\/06\/coquito.jpg","keywords":["Actores","Caracas","Coquito","Entretenimiento","Far\u00e1ndula","George Floyd","Nacionales","Racismo","Venezuela","Wilmer Machado"],"articleSection":["Fama"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/digital58.com.ve\/site\/2020\/06\/03\/el-mensaje-de-coquito-sobre-el-racismo-en-venezuela\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/digital58.com.ve\/site\/2020\/06\/03\/el-mensaje-de-coquito-sobre-el-racismo-en-venezuela\/","url":"https:\/\/digital58.com.ve\/site\/2020\/06\/03\/el-mensaje-de-coquito-sobre-el-racismo-en-venezuela\/","name":"El mensaje de Coquito sobre el racismo en Venezuela","isPartOf":{"@id":"https:\/\/digital58.com.ve\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/digital58.com.ve\/site\/2020\/06\/03\/el-mensaje-de-coquito-sobre-el-racismo-en-venezuela\/#primaryimage"},"image":{"@id":"https:\/\/digital58.com.ve\/site\/2020\/06\/03\/el-mensaje-de-coquito-sobre-el-racismo-en-venezuela\/#primaryimage"},"thumbnailUrl":"https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2020\/06\/coquito.jpg","datePublished":"2020-06-04T02:52:39+00:00","description":"Fama","breadcrumb":{"@id":"https:\/\/digital58.com.ve\/site\/2020\/06\/03\/el-mensaje-de-coquito-sobre-el-racismo-en-venezuela\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/digital58.com.ve\/site\/2020\/06\/03\/el-mensaje-de-coquito-sobre-el-racismo-en-venezuela\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/digital58.com.ve\/site\/2020\/06\/03\/el-mensaje-de-coquito-sobre-el-racismo-en-venezuela\/#primaryimage","url":"https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2020\/06\/coquito.jpg","contentUrl":"https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2020\/06\/coquito.jpg","width":607,"height":338},{"@type":"BreadcrumbList","@id":"https:\/\/digital58.com.ve\/site\/2020\/06\/03\/el-mensaje-de-coquito-sobre-el-racismo-en-venezuela\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/digital58.com.ve\/site\/"},{"@type":"ListItem","position":2,"name":"El mensaje de Coquito sobre el racismo en Venezuela"}]},{"@type":"WebSite","@id":"https:\/\/digital58.com.ve\/site\/#website","url":"https:\/\/digital58.com.ve\/site\/","name":"Noticias Digital58","description":"Portal de Noticias \u00a1Periodismo web de verdad! Lanzamiento web 22.11.2005 \/ Maracaibo, Venezuela","publisher":{"@id":"https:\/\/digital58.com.ve\/site\/#\/schema\/person\/64d1c2e4d0d4fd1b849980c4331c2951"},"alternateName":"ND58","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/digital58.com.ve\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/digital58.com.ve\/site\/#\/schema\/person\/64d1c2e4d0d4fd1b849980c4331c2951","name":"Villasmil Henry","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/bb0c4a2fcb7970138239f7e404ea75757b1b507b28b5ce4c53fbd62d797c5a7c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bb0c4a2fcb7970138239f7e404ea75757b1b507b28b5ce4c53fbd62d797c5a7c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bb0c4a2fcb7970138239f7e404ea75757b1b507b28b5ce4c53fbd62d797c5a7c?s=96&d=mm&r=g","caption":"Villasmil Henry"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/bb0c4a2fcb7970138239f7e404ea75757b1b507b28b5ce4c53fbd62d797c5a7c?s=96&d=mm&r=g"},"sameAs":["http:\/\/www.henryvillasmil.com.ve","https:\/\/www.instagram.com\/villasmilhfoto\/","https:\/\/x.com\/https:\/\/twitter.com\/villasmilhfoto"]},{"@type":"Person","@id":"https:\/\/digital58.com.ve\/site\/#\/schema\/person\/6672bab44ab958838204ebb2cb0e8d52","name":"Rubio Laura Isabel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f7cc56b26fb0562df4488ff129a58c3c1a1bd264c9af5f313a9b1797fff1cfb9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f7cc56b26fb0562df4488ff129a58c3c1a1bd264c9af5f313a9b1797fff1cfb9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f7cc56b26fb0562df4488ff129a58c3c1a1bd264c9af5f313a9b1797fff1cfb9?s=96&d=mm&r=g","caption":"Rubio Laura Isabel"},"url":"https:\/\/digital58.com.ve\/site\/author\/laurarubio\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2020\/06\/coquito.jpg",607,338,false],"thumbnail":["https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2020\/06\/coquito-150x150.jpg",150,150,true],"medium":["https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2020\/06\/coquito-300x167.jpg",300,167,true],"medium_large":["https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2020\/06\/coquito.jpg",607,338,false],"large":["https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2020\/06\/coquito.jpg",607,338,false],"1536x1536":["https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2020\/06\/coquito.jpg",607,338,false],"2048x2048":["https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2020\/06\/coquito.jpg",607,338,false],"colormag-highlighted-post":["https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2020\/06\/coquito.jpg",392,218,false],"colormag-featured-post-medium":["https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2020\/06\/coquito.jpg",368,205,false],"colormag-featured-post-small":["https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2020\/06\/coquito.jpg",130,72,false],"colormag-featured-image":["https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2020\/06\/coquito.jpg",607,338,false],"colormag-default-news":["https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2020\/06\/coquito.jpg",150,84,false],"colormag-featured-image-large":["https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2020\/06\/coquito.jpg",607,338,false]},"uagb_author_info":{"display_name":"Rubio Laura Isabel","author_link":"https:\/\/digital58.com.ve\/site\/author\/laurarubio\/"},"uagb_comment_info":0,"uagb_excerpt":"El actor venezolano Wilmer Machado, conocido como \u00abCoquito\u00bb, public\u00f3 un mensaje en su red social Instagram sobre el racismo, el","_links":{"self":[{"href":"https:\/\/digital58.com.ve\/site\/wp-json\/wp\/v2\/posts\/104355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digital58.com.ve\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/digital58.com.ve\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/digital58.com.ve\/site\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/digital58.com.ve\/site\/wp-json\/wp\/v2\/comments?post=104355"}],"version-history":[{"count":0,"href":"https:\/\/digital58.com.ve\/site\/wp-json\/wp\/v2\/posts\/104355\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/digital58.com.ve\/site\/wp-json\/wp\/v2\/media\/104421"}],"wp:attachment":[{"href":"https:\/\/digital58.com.ve\/site\/wp-json\/wp\/v2\/media?parent=104355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/digital58.com.ve\/site\/wp-json\/wp\/v2\/categories?post=104355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/digital58.com.ve\/site\/wp-json\/wp\/v2\/tags?post=104355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}