{"id":136807,"date":"2021-04-06T00:10:42","date_gmt":"2021-04-06T04:10:42","guid":{"rendered":"https:\/\/digital58.com.ve\/site\/?p=136807"},"modified":"2021-04-06T00:10:42","modified_gmt":"2021-04-06T04:10:42","slug":"venezuela-confirma-ocho-militares-muertos-en-combates-en-frontera-con-colombia","status":"publish","type":"post","link":"https:\/\/digital58.com.ve\/site\/2021\/04\/06\/venezuela-confirma-ocho-militares-muertos-en-combates-en-frontera-con-colombia\/","title":{"rendered":"Venezuela confirma ocho militares muertos en combates en frontera con Colombia"},"content":{"rendered":"<p><a href=\"https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2021\/04\/Vladimir-Padrino.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-136808\" src=\"https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2021\/04\/Vladimir-Padrino.jpg\" alt=\"\" width=\"900\" height=\"600\" srcset=\"https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2021\/04\/Vladimir-Padrino.jpg 800w, https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2021\/04\/Vladimir-Padrino-300x200.jpg 300w, https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2021\/04\/Vladimir-Padrino-768x512.jpg 768w, https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2021\/04\/Vladimir-Padrino-720x480.jpg 720w, https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2021\/04\/Vladimir-Padrino-480x320.jpg 480w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/a><\/p>\n<p>Las autoridades militares hab\u00edan confirmado hasta este domingo cuatro bajas en sus filas y la \u00abneutralizaci\u00f3n\u00bb de nueve \u00abterroristas\u00bb sin aclarar, hasta hoy, si hab\u00edan fallecido o sido detenidos.<\/p>\n<p><strong>Caracas, DC, Venezuela, 06 de abril de 2021 (ND58).-<\/strong> El ministro de Defensa de Venezuela, Vladimir Padrino, confirm\u00f3 este lunes que ocho militares han muerto \u2014el doble de los que se conoc\u00edan hasta el momento\u2014 durante los combates en una zona fronteriza con un grupo de disidentes de las FARC, del que han fallecido nueve miembros.<\/p>\n<p>\u00abHasta el presente se han dado nueve bajas de estos grupos terroristas y, lamentablemente, hemos sufrido la p\u00e9rdida de ocho compa\u00f1eros de la Fuerza Armada Nacional Bolivariana (FANB)\u00bb, dijo Padrino en una comparecencia sin preguntas acerca de los combates que comenzaron el pasado 21 de marzo en el estado de Apure (fronterizo con Colombia).<\/p>\n<p>La informaci\u00f3n difundida hasta el momento por fuentes castrenses u oficiales ha sido muy escasa y ni siquiera han aclarado a qu\u00e9 grupo armado se enfrentan, pese a que han difundido fotos de uniformes incautados con los logos y las siglas de la antigua guerrilla de las FARC.<\/p>\n<p>Tambi\u00e9n varias asociaciones con miembros en la zona han confirmado que se trata de disidentes de las FARC.<\/p>\n<p>Padrino tampoco confirm\u00f3 de qu\u00e9 grupo forman parte los miembros de la banda contra la que combaten y que, adem\u00e1s de los ocho fallecidos, ha provocado heridas a 34 uniformados \u00abque han recibido asistencia medica en la red de salud militar\u00bb, de los que 21 \u00abhan salido de alta con todos sus tratamientos\u00bb.<\/p>\n<p>Durante el operativo, han desactivado 16 minas antipersona instaladas por el grupo armado que, reconoci\u00f3, ha afectado a soldados y \u00abmedios terrestres del ej\u00e9rcito\u00bb, adem\u00e1s de desmantelar seis campamentos.<\/p>\n<p><strong>Activan zona de defensa especial<\/strong><\/p>\n<p>Padrino coment\u00f3 que, por orden del presidente Nicol\u00e1s Maduro, se ha activado una \u00abzona operativa de defensa integral temporal especial\u00bb en el \u00e1rea, que estar\u00e1 comandada por el general de divisi\u00f3n Alejando Javier Benitez Marcano con \u00abun estado mayor de coordinaci\u00f3n\u00bb.<\/p>\n<p>Tambi\u00e9n activaron una brigada integral, denominada Negro Primero, bajo el mando del general Wilfredo Alexander Medrano, \u00aba quien se le asignar\u00e1n las unidades militares y equipos que sean necesarios\u00bb.<\/p>\n<p>Asimismo, el ministro de Defensa explic\u00f3 que Maduro \u00abha ordenado medidas extraordinarias\u00bb, que incluyen la conformaci\u00f3n de \u00abuna zona de seguridad en los municipios P\u00e1ez, Mu\u00f1oz y Romulo Gallegos\u00bb, todos ellos en Apure y en donde se han desarrollado la mayor\u00eda de los combates.<\/p>\n<p>Como parte de esas mediadas, el Comando Estrat\u00e9gico Operacional de la FANB dise\u00f1ar\u00e1 y ejecutar\u00e1 \u00abplanes especiales de seguridad p\u00fablica que hagan frente a las acciones desestabilizadoras\u00bb que atenten contra la paz, la seguridad personal y \u00abel resguardo de instalaciones y bienes p\u00fablicos y privados\u00bb para \u00abgarantizar el orden interno, la paz ciudadana y los derechos humanos\u00bb.<\/p>\n<p>Asimismo, coment\u00f3 que ese comando, a trav\u00e9s de la zona operativa de defensa integral de Apure y conjuntamente con las autoridades civiles, regionales y municipales, \u00aba los fines de resguardar los derechos humanos\u00bb, establecer\u00e1n restricciones y horarios para el tr\u00e1nsito.<\/p>\n<p>Del mismo modo, impondr\u00e1n \u00abrestricciones de horarios para funcionamiento de lugares p\u00fablicos y privados\u00bb, adem\u00e1s de poner en marcha medidas de control de seguridad \u00abpara garantizar los servicios p\u00fablicos y la paz ciudadana\u00bb.<\/p>\n<p><strong>Los militares har\u00e1n inspecciones<\/strong><\/p>\n<p>Finalmente, Padrino aclar\u00f3 que los militares desplegados en la zona \u00abpodr\u00e1n realizar inspecci\u00f3n en propiedades muebles e inmuebles de conformidad a las leyes y reglamentos vigentes\u00bb, as\u00ed como \u00abdesalojar ocupaciones ilegales de bienes p\u00fablicos que afecten a la seguridad y defensa de la naci\u00f3n\u00bb.<\/p>\n<p>Tambi\u00e9n advirti\u00f3 que las unidades militares \u00abintervendr\u00e1n para restablecer el libre tr\u00e1nsito en zonas urbanas o rurales en caso de que este sea interrumpido\u00bb, adem\u00e1s de poner en marcha \u00abotras acciones que garanticen el libre desenvolvimiento y la paz en la regi\u00f3n\u00bb.<\/p>\n<p>Seg\u00fan el ministro, tras tres semanas de enfrentamientos y 17 muertos, \u00abla regi\u00f3n est\u00e1 volviendo a la normalidad\u00bb.<\/p><div class=\"fglpt6a57202dd9935\" ><p style=\"text-align: center;\"><a href=\"https:\/\/t.me\/noticiasdigital58\" target=\"_blank\" rel=\"noopener\"><img class=\"aligncenter size-full wp-image-125363\" src=\"https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2021\/04\/banner-telegram-web-2021.png\" alt=\"\" width=\"600\" height=\"90\" \/><\/a><\/p><\/div><style type=\"text\/css\">\r\n@media screen and (min-width: 1201px) {\r\n.fglpt6a57202dd9935 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.fglpt6a57202dd9935 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.fglpt6a57202dd9935 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.fglpt6a57202dd9935 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.fglpt6a57202dd9935 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n\n<p><strong>Redacci\u00f3n ND58 | Fuente: EFE<\/strong><br \/>\n<strong>Edici\u00f3n: Villasmil, Henry<\/strong><br \/>\n<strong>Gr\u00e1fica: EFE<\/strong><\/p>\n<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div>","protected":false},"excerpt":{"rendered":"<p>Las autoridades militares hab\u00edan confirmado hasta este domingo cuatro bajas en sus filas y la \u00abneutralizaci\u00f3n\u00bb de nueve \u00abterroristas\u00bb sin<\/p>\n","protected":false},"author":1,"featured_media":136808,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_uag_custom_page_level_css":"","footnotes":""},"categories":[16454],"tags":[13537,98,13766,15073,12064,11997,16818,22505,14946],"class_list":["post-136807","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-venezuela","tag-apure","tag-colombia","tag-fallecidos","tag-farc","tag-frontera","tag-fuerza-armada-nacional-bolivariana","tag-militares","tag-ministro-de-defensa","tag-vladimir-padrino"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Venezuela confirma ocho militares muertos en combates en frontera con Colombia<\/title>\n<meta name=\"description\" content=\"Venezuela\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/digital58.com.ve\/site\/2021\/04\/06\/venezuela-confirma-ocho-militares-muertos-en-combates-en-frontera-con-colombia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Venezuela confirma ocho militares muertos en combates en frontera con Colombia\" \/>\n<meta property=\"og:description\" content=\"Venezuela\" \/>\n<meta property=\"og:url\" content=\"https:\/\/digital58.com.ve\/site\/2021\/04\/06\/venezuela-confirma-ocho-militares-muertos-en-combates-en-frontera-con-colombia\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Digital58\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-06T04:10:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2021\/04\/Vladimir-Padrino.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Villasmil Henry\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/villasmilhfoto\" \/>\n<meta name=\"twitter:site\" content=\"@villasmilhfoto\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Villasmil Henry\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/2021\\\/04\\\/06\\\/venezuela-confirma-ocho-militares-muertos-en-combates-en-frontera-con-colombia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/2021\\\/04\\\/06\\\/venezuela-confirma-ocho-militares-muertos-en-combates-en-frontera-con-colombia\\\/\"},\"author\":{\"name\":\"Villasmil Henry\",\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/#\\\/schema\\\/person\\\/64d1c2e4d0d4fd1b849980c4331c2951\"},\"headline\":\"Venezuela confirma ocho militares muertos en combates en frontera con Colombia\",\"datePublished\":\"2021-04-06T04:10:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/2021\\\/04\\\/06\\\/venezuela-confirma-ocho-militares-muertos-en-combates-en-frontera-con-colombia\\\/\"},\"wordCount\":704,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/#\\\/schema\\\/person\\\/64d1c2e4d0d4fd1b849980c4331c2951\"},\"image\":{\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/2021\\\/04\\\/06\\\/venezuela-confirma-ocho-militares-muertos-en-combates-en-frontera-con-colombia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Vladimir-Padrino.jpg\",\"keywords\":[\"Apure\",\"Colombia\",\"Fallecidos\",\"FARC\",\"Frontera\",\"Fuerza Armada Nacional Bolivariana\",\"militares\",\"Ministro de Defensa\",\"Vladimir Padrino\"],\"articleSection\":[\"Venezuela\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/digital58.com.ve\\\/site\\\/2021\\\/04\\\/06\\\/venezuela-confirma-ocho-militares-muertos-en-combates-en-frontera-con-colombia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/2021\\\/04\\\/06\\\/venezuela-confirma-ocho-militares-muertos-en-combates-en-frontera-con-colombia\\\/\",\"url\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/2021\\\/04\\\/06\\\/venezuela-confirma-ocho-militares-muertos-en-combates-en-frontera-con-colombia\\\/\",\"name\":\"Venezuela confirma ocho militares muertos en combates en frontera con Colombia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/2021\\\/04\\\/06\\\/venezuela-confirma-ocho-militares-muertos-en-combates-en-frontera-con-colombia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/2021\\\/04\\\/06\\\/venezuela-confirma-ocho-militares-muertos-en-combates-en-frontera-con-colombia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Vladimir-Padrino.jpg\",\"datePublished\":\"2021-04-06T04:10:42+00:00\",\"description\":\"Venezuela\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/2021\\\/04\\\/06\\\/venezuela-confirma-ocho-militares-muertos-en-combates-en-frontera-con-colombia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/digital58.com.ve\\\/site\\\/2021\\\/04\\\/06\\\/venezuela-confirma-ocho-militares-muertos-en-combates-en-frontera-con-colombia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/2021\\\/04\\\/06\\\/venezuela-confirma-ocho-militares-muertos-en-combates-en-frontera-con-colombia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Vladimir-Padrino.jpg\",\"contentUrl\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Vladimir-Padrino.jpg\",\"width\":800,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/2021\\\/04\\\/06\\\/venezuela-confirma-ocho-militares-muertos-en-combates-en-frontera-con-colombia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Venezuela confirma ocho militares muertos en combates en frontera con Colombia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/\",\"name\":\"Noticias Digital58\",\"description\":\"Portal de Noticias \u00a1Periodismo web de verdad! Lanzamiento web 22.11.2005 \\\/ Maracaibo, Venezuela\",\"publisher\":{\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/#\\\/schema\\\/person\\\/64d1c2e4d0d4fd1b849980c4331c2951\"},\"alternateName\":\"ND58\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/#\\\/schema\\\/person\\\/64d1c2e4d0d4fd1b849980c4331c2951\",\"name\":\"Villasmil Henry\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb0c4a2fcb7970138239f7e404ea75757b1b507b28b5ce4c53fbd62d797c5a7c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb0c4a2fcb7970138239f7e404ea75757b1b507b28b5ce4c53fbd62d797c5a7c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb0c4a2fcb7970138239f7e404ea75757b1b507b28b5ce4c53fbd62d797c5a7c?s=96&d=mm&r=g\",\"caption\":\"Villasmil Henry\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb0c4a2fcb7970138239f7e404ea75757b1b507b28b5ce4c53fbd62d797c5a7c?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/www.henryvillasmil.com.ve\",\"https:\\\/\\\/www.instagram.com\\\/villasmilhfoto\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/villasmilhfoto\"],\"url\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/author\\\/droopy_68\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Venezuela confirma ocho militares muertos en combates en frontera con Colombia","description":"Venezuela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/digital58.com.ve\/site\/2021\/04\/06\/venezuela-confirma-ocho-militares-muertos-en-combates-en-frontera-con-colombia\/","og_locale":"es_ES","og_type":"article","og_title":"Venezuela confirma ocho militares muertos en combates en frontera con Colombia","og_description":"Venezuela","og_url":"https:\/\/digital58.com.ve\/site\/2021\/04\/06\/venezuela-confirma-ocho-militares-muertos-en-combates-en-frontera-con-colombia\/","og_site_name":"Noticias Digital58","article_published_time":"2021-04-06T04:10:42+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2021\/04\/Vladimir-Padrino.jpg","type":"image\/jpeg"}],"author":"Villasmil Henry","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/villasmilhfoto","twitter_site":"@villasmilhfoto","twitter_misc":{"Escrito por":"Villasmil Henry","Tiempo estimado de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/digital58.com.ve\/site\/2021\/04\/06\/venezuela-confirma-ocho-militares-muertos-en-combates-en-frontera-con-colombia\/#article","isPartOf":{"@id":"https:\/\/digital58.com.ve\/site\/2021\/04\/06\/venezuela-confirma-ocho-militares-muertos-en-combates-en-frontera-con-colombia\/"},"author":{"name":"Villasmil Henry","@id":"https:\/\/digital58.com.ve\/site\/#\/schema\/person\/64d1c2e4d0d4fd1b849980c4331c2951"},"headline":"Venezuela confirma ocho militares muertos en combates en frontera con Colombia","datePublished":"2021-04-06T04:10:42+00:00","mainEntityOfPage":{"@id":"https:\/\/digital58.com.ve\/site\/2021\/04\/06\/venezuela-confirma-ocho-militares-muertos-en-combates-en-frontera-con-colombia\/"},"wordCount":704,"commentCount":0,"publisher":{"@id":"https:\/\/digital58.com.ve\/site\/#\/schema\/person\/64d1c2e4d0d4fd1b849980c4331c2951"},"image":{"@id":"https:\/\/digital58.com.ve\/site\/2021\/04\/06\/venezuela-confirma-ocho-militares-muertos-en-combates-en-frontera-con-colombia\/#primaryimage"},"thumbnailUrl":"https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2021\/04\/Vladimir-Padrino.jpg","keywords":["Apure","Colombia","Fallecidos","FARC","Frontera","Fuerza Armada Nacional Bolivariana","militares","Ministro de Defensa","Vladimir Padrino"],"articleSection":["Venezuela"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/digital58.com.ve\/site\/2021\/04\/06\/venezuela-confirma-ocho-militares-muertos-en-combates-en-frontera-con-colombia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/digital58.com.ve\/site\/2021\/04\/06\/venezuela-confirma-ocho-militares-muertos-en-combates-en-frontera-con-colombia\/","url":"https:\/\/digital58.com.ve\/site\/2021\/04\/06\/venezuela-confirma-ocho-militares-muertos-en-combates-en-frontera-con-colombia\/","name":"Venezuela confirma ocho militares muertos en combates en frontera con Colombia","isPartOf":{"@id":"https:\/\/digital58.com.ve\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/digital58.com.ve\/site\/2021\/04\/06\/venezuela-confirma-ocho-militares-muertos-en-combates-en-frontera-con-colombia\/#primaryimage"},"image":{"@id":"https:\/\/digital58.com.ve\/site\/2021\/04\/06\/venezuela-confirma-ocho-militares-muertos-en-combates-en-frontera-con-colombia\/#primaryimage"},"thumbnailUrl":"https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2021\/04\/Vladimir-Padrino.jpg","datePublished":"2021-04-06T04:10:42+00:00","description":"Venezuela","breadcrumb":{"@id":"https:\/\/digital58.com.ve\/site\/2021\/04\/06\/venezuela-confirma-ocho-militares-muertos-en-combates-en-frontera-con-colombia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/digital58.com.ve\/site\/2021\/04\/06\/venezuela-confirma-ocho-militares-muertos-en-combates-en-frontera-con-colombia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/digital58.com.ve\/site\/2021\/04\/06\/venezuela-confirma-ocho-militares-muertos-en-combates-en-frontera-con-colombia\/#primaryimage","url":"https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2021\/04\/Vladimir-Padrino.jpg","contentUrl":"https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2021\/04\/Vladimir-Padrino.jpg","width":800,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/digital58.com.ve\/site\/2021\/04\/06\/venezuela-confirma-ocho-militares-muertos-en-combates-en-frontera-con-colombia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/digital58.com.ve\/site\/"},{"@type":"ListItem","position":2,"name":"Venezuela confirma ocho militares muertos en combates en frontera con Colombia"}]},{"@type":"WebSite","@id":"https:\/\/digital58.com.ve\/site\/#website","url":"https:\/\/digital58.com.ve\/site\/","name":"Noticias Digital58","description":"Portal de Noticias \u00a1Periodismo web de verdad! Lanzamiento web 22.11.2005 \/ Maracaibo, Venezuela","publisher":{"@id":"https:\/\/digital58.com.ve\/site\/#\/schema\/person\/64d1c2e4d0d4fd1b849980c4331c2951"},"alternateName":"ND58","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/digital58.com.ve\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/digital58.com.ve\/site\/#\/schema\/person\/64d1c2e4d0d4fd1b849980c4331c2951","name":"Villasmil Henry","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/bb0c4a2fcb7970138239f7e404ea75757b1b507b28b5ce4c53fbd62d797c5a7c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bb0c4a2fcb7970138239f7e404ea75757b1b507b28b5ce4c53fbd62d797c5a7c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bb0c4a2fcb7970138239f7e404ea75757b1b507b28b5ce4c53fbd62d797c5a7c?s=96&d=mm&r=g","caption":"Villasmil Henry"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/bb0c4a2fcb7970138239f7e404ea75757b1b507b28b5ce4c53fbd62d797c5a7c?s=96&d=mm&r=g"},"sameAs":["http:\/\/www.henryvillasmil.com.ve","https:\/\/www.instagram.com\/villasmilhfoto\/","https:\/\/x.com\/https:\/\/twitter.com\/villasmilhfoto"],"url":"https:\/\/digital58.com.ve\/site\/author\/droopy_68\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2021\/04\/Vladimir-Padrino.jpg",800,533,false],"thumbnail":["https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2021\/04\/Vladimir-Padrino-150x150.jpg",150,150,true],"medium":["https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2021\/04\/Vladimir-Padrino-300x200.jpg",300,200,true],"medium_large":["https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2021\/04\/Vladimir-Padrino-768x512.jpg",768,512,true],"large":["https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2021\/04\/Vladimir-Padrino.jpg",800,533,false],"1536x1536":["https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2021\/04\/Vladimir-Padrino.jpg",800,533,false],"2048x2048":["https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2021\/04\/Vladimir-Padrino.jpg",800,533,false],"colormag-highlighted-post":["https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2021\/04\/Vladimir-Padrino.jpg",392,261,false],"colormag-featured-post-medium":["https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2021\/04\/Vladimir-Padrino.jpg",308,205,false],"colormag-featured-post-small":["https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2021\/04\/Vladimir-Padrino.jpg",130,87,false],"colormag-featured-image":["https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2021\/04\/Vladimir-Padrino.jpg",668,445,false],"colormag-default-news":["https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2021\/04\/Vladimir-Padrino.jpg",150,100,false],"colormag-featured-image-large":["https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2021\/04\/Vladimir-Padrino.jpg",800,533,false]},"uagb_author_info":{"display_name":"Villasmil Henry","author_link":"https:\/\/digital58.com.ve\/site\/author\/droopy_68\/"},"uagb_comment_info":0,"uagb_excerpt":"Las autoridades militares hab\u00edan confirmado hasta este domingo cuatro bajas en sus filas y la \u00abneutralizaci\u00f3n\u00bb de nueve \u00abterroristas\u00bb sin","_links":{"self":[{"href":"https:\/\/digital58.com.ve\/site\/wp-json\/wp\/v2\/posts\/136807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digital58.com.ve\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/digital58.com.ve\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/digital58.com.ve\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/digital58.com.ve\/site\/wp-json\/wp\/v2\/comments?post=136807"}],"version-history":[{"count":0,"href":"https:\/\/digital58.com.ve\/site\/wp-json\/wp\/v2\/posts\/136807\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/digital58.com.ve\/site\/wp-json\/wp\/v2\/media\/136808"}],"wp:attachment":[{"href":"https:\/\/digital58.com.ve\/site\/wp-json\/wp\/v2\/media?parent=136807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/digital58.com.ve\/site\/wp-json\/wp\/v2\/categories?post=136807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/digital58.com.ve\/site\/wp-json\/wp\/v2\/tags?post=136807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}