{"id":170019,"date":"2023-08-24T23:03:54","date_gmt":"2023-08-25T03:03:54","guid":{"rendered":"https:\/\/digital58.com.ve\/site\/?p=170019"},"modified":"2023-08-24T23:03:54","modified_gmt":"2023-08-25T03:03:54","slug":"voleibol-la-gaita-silencio-al-joropo-de-guarico-y-zulia-avanza-invicto-en-busca-de-la-semifinal","status":"publish","type":"post","link":"https:\/\/digital58.com.ve\/site\/2023\/08\/24\/voleibol-la-gaita-silencio-al-joropo-de-guarico-y-zulia-avanza-invicto-en-busca-de-la-semifinal\/","title":{"rendered":"#Voleibol | La gaita silenci\u00f3 al joropo de Gu\u00e1rico y Zulia avanza invicto en busca de la semifinal"},"content":{"rendered":"<p><a href=\"https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2023\/08\/voleibol-zulia-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-170024\" src=\"https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2023\/08\/voleibol-zulia-2.jpg\" alt=\"\" width=\"800\" height=\"480\" srcset=\"https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2023\/08\/voleibol-zulia-2.jpg 800w, https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2023\/08\/voleibol-zulia-2-300x180.jpg 300w, https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2023\/08\/voleibol-zulia-2-768x461.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>Los defensores de la casa se llevaron el trofeo alcald\u00eda de Maracaibo, que entreg\u00f3 el alcalde Rafael Ram\u00edrez<\/p>\n<p><strong>Maracaibo, Zulia, Venezuela, 24 de agosto de 2023 (ND58).-<\/strong> Los inspirados muchachos de la selecci\u00f3n del Zulia derrotaron a Gu\u00e1rico 3-0, este jueves, avanzando invictos y de primeros del Grupo A en el Campeonato Nacional de Voleibol Juvenil, que se juega en Maracaibo.<\/p>\n<p>La aguerrida tropa que dirige Danny Malav\u00e9 no confront\u00f3 mayores problemas frente a los llaneros, que se despiden del evento con tres derrotas y una sola victoria.<\/p>\n<p><a href=\"https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2023\/08\/voleibol-zulia-4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-170022\" src=\"https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2023\/08\/voleibol-zulia-4.jpg\" alt=\"\" width=\"800\" height=\"494\" srcset=\"https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2023\/08\/voleibol-zulia-4.jpg 800w, https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2023\/08\/voleibol-zulia-4-300x185.jpg 300w, https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2023\/08\/voleibol-zulia-4-768x474.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>Con su triunfo el equipo de Zulia alz\u00f3 la Copa alcald\u00eda de Maracaibo, que entreg\u00f3 la m\u00e1xima autoridad del municipio, Rafael Ram\u00edrez Colina.<\/p>\n<p>En el papel Zulia luce favorito para avanzar a la semifinal. Gan\u00f3 los tres partidos preliminares en un grupo relativamente f\u00e1cil y le toca contra en teor\u00eda el m\u00e1s \u00abd\u00e9bil\u00bb de Grupo B. Los centauros portuguese\u00f1os clasificaron como el mejor tercero con dos ganados y tres perdidos.<\/p>\n<p><a href=\"https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2023\/08\/voleibol-zulia-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-170023\" src=\"https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2023\/08\/voleibol-zulia-3.jpg\" alt=\"\" width=\"800\" height=\"496\" srcset=\"https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2023\/08\/voleibol-zulia-3.jpg 800w, https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2023\/08\/voleibol-zulia-3-300x186.jpg 300w, https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2023\/08\/voleibol-zulia-3-768x476.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>\u00abNosotros vamos a mantener nuestro planteamiento ofensivo ante Portuguesa con Carlos Berr\u00edos y Franchesco Capillo como lo hemos venido haciendo. Sin menospreciar al rival, en el papel no se ve un equipo tan fuerte, pero en el voleibol nada est\u00e1 escrito. Hay que salir con todo a ganar ese juego\u00bb, dijo el asistente t\u00e9cnico de la selecci\u00f3n R\u00e9gulo Vargas.<\/p>\n<p>Con este partido cerrar\u00e1 la jornada de cuartos de final y se realizar\u00e1 a las cuatro de la tarde en el gimnasio cubierto Pedro El\u00edas Belisario Aponte de Maracaibo.<\/p>\n<p><strong>Los otros cruces<\/strong><\/p>\n<p>El resto de la jornada por los otros tres boletos a semifinales se jugar\u00e1 con el siguiente cronograma:<\/p>\n<p>A las 10:00 a.m. se enfrentar\u00e1n Carabobo y Aragua. Los carabobe\u00f1os clasificaron invictos en el grupo B mientras Aragua pas\u00f3 como el mejor tercero del Grupo C.<\/p>\n<p>A las 12:00 m. chocar\u00e1n Apure y Miranda. Los llaneros clasificaron como segundos del grupo A con dos ganados y uno perdido y Miranda segundo del C con tres ganados y uno perdido.<\/p>\n<p>El juego de las 2:00 p.m. ser\u00e1 protagonizado por Lara y Distrito Capital. Los crepusculares avanzaron como el mejor segundo del grupo B mientras Distrito lo hizo liderando invicto el Grupo C con cuatro victorias sin derrotas.<\/p>\n<p><a href=\"https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2023\/08\/voleibol-zulia-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-170025\" src=\"https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2023\/08\/voleibol-zulia-1.jpg\" alt=\"\" width=\"800\" height=\"499\" srcset=\"https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2023\/08\/voleibol-zulia-1.jpg 800w, https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2023\/08\/voleibol-zulia-1-300x187.jpg 300w, https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2023\/08\/voleibol-zulia-1-768x479.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>Y por \u00faltimo, en el juego bonito de la jornada, se ver\u00e1n las caras los defensores de la casa y Portuguesa, a las 4:00 p.m.<\/p>\n<p>Las autoridades deportivas del estado, del municipio Maracaibo y San Francisco as\u00ed como el comit\u00e9 organizador y la Asociaci\u00f3n de Voleibol del estado Zulia invitan a toda la fanaticada del juego de la malla alta y del deporte en general a disfrutar un emocionante espect\u00e1culo y a apoyar a la selecci\u00f3n de azul y negro como el s\u00e9ptimo jugador desde las tribunas.<\/p>\n<p><strong>Redacci\u00f3n ND58 | Fuente: Prensa Comit\u00e9 Organizador<\/strong><br \/>\n<strong>Edici\u00f3n: Villasmil, Henry<\/strong><br \/>\n<strong>Gr\u00e1ficas: Prensa Comit\u00e9 Organizador<\/strong><\/p>\n<p>&nbsp;<\/p><div class=\"qkogc6a03c285c15b1\" ><p style=\"text-align: center;\"><a href=\"https:\/\/t.me\/noticiasdigital58\" target=\"_blank\" rel=\"noopener\"><img class=\"aligncenter size-full wp-image-125363\" src=\"https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2021\/04\/banner-telegram-web-2021.png\" alt=\"\" width=\"600\" height=\"90\" \/><\/a><\/p><\/div><style type=\"text\/css\">\r\n@media screen and (min-width: 1201px) {\r\n.qkogc6a03c285c15b1 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.qkogc6a03c285c15b1 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.qkogc6a03c285c15b1 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.qkogc6a03c285c15b1 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.qkogc6a03c285c15b1 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n\n<p>&nbsp;<\/p>\n<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div>","protected":false},"excerpt":{"rendered":"<p>Los defensores de la casa se llevaron el trofeo alcald\u00eda de Maracaibo, que entreg\u00f3 el alcalde Rafael Ram\u00edrez Maracaibo, Zulia,<\/p>\n","protected":false},"author":1,"featured_media":170023,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_uag_custom_page_level_css":"","footnotes":""},"categories":[5402],"tags":[32272,28831,73,233,2354,32,185,32240,186,761],"class_list":["post-170019","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","tag-campeonato-nacional-de-voleibol-juvenil","tag-gimnasio-cubierto-pedro-elias-belisario-aponte","tag-maracaibo","tag-nacionales","tag-regionales","tag-venezuela","tag-voleibol","tag-voleibol-nacional","tag-voleibol-venezolano","tag-zulia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>#Voleibol | La gaita silenci\u00f3 al joropo de Gu\u00e1rico y Zulia avanza invicto en busca de la semifinal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/digital58.com.ve\/site\/2023\/08\/24\/voleibol-la-gaita-silencio-al-joropo-de-guarico-y-zulia-avanza-invicto-en-busca-de-la-semifinal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"#Voleibol | La gaita silenci\u00f3 al joropo de Gu\u00e1rico y Zulia avanza invicto en busca de la semifinal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/digital58.com.ve\/site\/2023\/08\/24\/voleibol-la-gaita-silencio-al-joropo-de-guarico-y-zulia-avanza-invicto-en-busca-de-la-semifinal\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Digital58\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-25T03:03:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/digital58.com.ve\/site\/wp-content\/uploads\/2023\/08\/voleibol-zulia-3.jpg?fit=800%2C496&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"496\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Villasmil Henry\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/villasmilhfoto\" \/>\n<meta name=\"twitter:site\" content=\"@villasmilhfoto\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Villasmil Henry\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/2023\\\/08\\\/24\\\/voleibol-la-gaita-silencio-al-joropo-de-guarico-y-zulia-avanza-invicto-en-busca-de-la-semifinal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/2023\\\/08\\\/24\\\/voleibol-la-gaita-silencio-al-joropo-de-guarico-y-zulia-avanza-invicto-en-busca-de-la-semifinal\\\/\"},\"author\":{\"name\":\"Villasmil Henry\",\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/#\\\/schema\\\/person\\\/64d1c2e4d0d4fd1b849980c4331c2951\"},\"headline\":\"#Voleibol | La gaita silenci\u00f3 al joropo de Gu\u00e1rico y Zulia avanza invicto en busca de la semifinal\",\"datePublished\":\"2023-08-25T03:03:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/2023\\\/08\\\/24\\\/voleibol-la-gaita-silencio-al-joropo-de-guarico-y-zulia-avanza-invicto-en-busca-de-la-semifinal\\\/\"},\"wordCount\":510,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/#\\\/schema\\\/person\\\/64d1c2e4d0d4fd1b849980c4331c2951\"},\"image\":{\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/2023\\\/08\\\/24\\\/voleibol-la-gaita-silencio-al-joropo-de-guarico-y-zulia-avanza-invicto-en-busca-de-la-semifinal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/voleibol-zulia-3.jpg\",\"keywords\":[\"Campeonato Nacional de Voleibol Juvenil\",\"Gimnasio cubierto Pedro El\u00edas Belisario Aponte\",\"Maracaibo\",\"Nacionales\",\"Regionales\",\"Venezuela\",\"Voleibol\",\"Voleibol nacional\",\"Voleibol Venezolano\",\"Zulia\"],\"articleSection\":[\"Deportes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/digital58.com.ve\\\/site\\\/2023\\\/08\\\/24\\\/voleibol-la-gaita-silencio-al-joropo-de-guarico-y-zulia-avanza-invicto-en-busca-de-la-semifinal\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/2023\\\/08\\\/24\\\/voleibol-la-gaita-silencio-al-joropo-de-guarico-y-zulia-avanza-invicto-en-busca-de-la-semifinal\\\/\",\"url\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/2023\\\/08\\\/24\\\/voleibol-la-gaita-silencio-al-joropo-de-guarico-y-zulia-avanza-invicto-en-busca-de-la-semifinal\\\/\",\"name\":\"#Voleibol | La gaita silenci\u00f3 al joropo de Gu\u00e1rico y Zulia avanza invicto en busca de la semifinal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/2023\\\/08\\\/24\\\/voleibol-la-gaita-silencio-al-joropo-de-guarico-y-zulia-avanza-invicto-en-busca-de-la-semifinal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/2023\\\/08\\\/24\\\/voleibol-la-gaita-silencio-al-joropo-de-guarico-y-zulia-avanza-invicto-en-busca-de-la-semifinal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/voleibol-zulia-3.jpg\",\"datePublished\":\"2023-08-25T03:03:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/2023\\\/08\\\/24\\\/voleibol-la-gaita-silencio-al-joropo-de-guarico-y-zulia-avanza-invicto-en-busca-de-la-semifinal\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/digital58.com.ve\\\/site\\\/2023\\\/08\\\/24\\\/voleibol-la-gaita-silencio-al-joropo-de-guarico-y-zulia-avanza-invicto-en-busca-de-la-semifinal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/2023\\\/08\\\/24\\\/voleibol-la-gaita-silencio-al-joropo-de-guarico-y-zulia-avanza-invicto-en-busca-de-la-semifinal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/voleibol-zulia-3.jpg\",\"contentUrl\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/voleibol-zulia-3.jpg\",\"width\":800,\"height\":496},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/2023\\\/08\\\/24\\\/voleibol-la-gaita-silencio-al-joropo-de-guarico-y-zulia-avanza-invicto-en-busca-de-la-semifinal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"#Voleibol | La gaita silenci\u00f3 al joropo de Gu\u00e1rico y Zulia avanza invicto en busca de la semifinal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/\",\"name\":\"Noticias Digital58\",\"description\":\"Portal de Noticias \u00a1Periodismo web de verdad! Lanzamiento web 22.11.2005 \\\/ Maracaibo, Venezuela\",\"publisher\":{\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/#\\\/schema\\\/person\\\/64d1c2e4d0d4fd1b849980c4331c2951\"},\"alternateName\":\"ND58\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/#\\\/schema\\\/person\\\/64d1c2e4d0d4fd1b849980c4331c2951\",\"name\":\"Villasmil Henry\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb0c4a2fcb7970138239f7e404ea75757b1b507b28b5ce4c53fbd62d797c5a7c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb0c4a2fcb7970138239f7e404ea75757b1b507b28b5ce4c53fbd62d797c5a7c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb0c4a2fcb7970138239f7e404ea75757b1b507b28b5ce4c53fbd62d797c5a7c?s=96&d=mm&r=g\",\"caption\":\"Villasmil Henry\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb0c4a2fcb7970138239f7e404ea75757b1b507b28b5ce4c53fbd62d797c5a7c?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/www.henryvillasmil.com.ve\",\"https:\\\/\\\/www.instagram.com\\\/villasmilhfoto\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/villasmilhfoto\"],\"url\":\"https:\\\/\\\/digital58.com.ve\\\/site\\\/author\\\/droopy_68\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"#Voleibol | La gaita silenci\u00f3 al joropo de Gu\u00e1rico y Zulia avanza invicto en busca de la semifinal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/digital58.com.ve\/site\/2023\/08\/24\/voleibol-la-gaita-silencio-al-joropo-de-guarico-y-zulia-avanza-invicto-en-busca-de-la-semifinal\/","og_locale":"es_ES","og_type":"article","og_title":"#Voleibol | La gaita silenci\u00f3 al joropo de Gu\u00e1rico y Zulia avanza invicto en busca de la semifinal","og_url":"https:\/\/digital58.com.ve\/site\/2023\/08\/24\/voleibol-la-gaita-silencio-al-joropo-de-guarico-y-zulia-avanza-invicto-en-busca-de-la-semifinal\/","og_site_name":"Noticias Digital58","article_published_time":"2023-08-25T03:03:54+00:00","og_image":[{"width":800,"height":496,"url":"https:\/\/i0.wp.com\/digital58.com.ve\/site\/wp-content\/uploads\/2023\/08\/voleibol-zulia-3.jpg?fit=800%2C496&ssl=1","type":"image\/jpeg"}],"author":"Villasmil Henry","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/villasmilhfoto","twitter_site":"@villasmilhfoto","twitter_misc":{"Escrito por":"Villasmil Henry","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/digital58.com.ve\/site\/2023\/08\/24\/voleibol-la-gaita-silencio-al-joropo-de-guarico-y-zulia-avanza-invicto-en-busca-de-la-semifinal\/#article","isPartOf":{"@id":"https:\/\/digital58.com.ve\/site\/2023\/08\/24\/voleibol-la-gaita-silencio-al-joropo-de-guarico-y-zulia-avanza-invicto-en-busca-de-la-semifinal\/"},"author":{"name":"Villasmil Henry","@id":"https:\/\/digital58.com.ve\/site\/#\/schema\/person\/64d1c2e4d0d4fd1b849980c4331c2951"},"headline":"#Voleibol | La gaita silenci\u00f3 al joropo de Gu\u00e1rico y Zulia avanza invicto en busca de la semifinal","datePublished":"2023-08-25T03:03:54+00:00","mainEntityOfPage":{"@id":"https:\/\/digital58.com.ve\/site\/2023\/08\/24\/voleibol-la-gaita-silencio-al-joropo-de-guarico-y-zulia-avanza-invicto-en-busca-de-la-semifinal\/"},"wordCount":510,"commentCount":0,"publisher":{"@id":"https:\/\/digital58.com.ve\/site\/#\/schema\/person\/64d1c2e4d0d4fd1b849980c4331c2951"},"image":{"@id":"https:\/\/digital58.com.ve\/site\/2023\/08\/24\/voleibol-la-gaita-silencio-al-joropo-de-guarico-y-zulia-avanza-invicto-en-busca-de-la-semifinal\/#primaryimage"},"thumbnailUrl":"https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2023\/08\/voleibol-zulia-3.jpg","keywords":["Campeonato Nacional de Voleibol Juvenil","Gimnasio cubierto Pedro El\u00edas Belisario Aponte","Maracaibo","Nacionales","Regionales","Venezuela","Voleibol","Voleibol nacional","Voleibol Venezolano","Zulia"],"articleSection":["Deportes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/digital58.com.ve\/site\/2023\/08\/24\/voleibol-la-gaita-silencio-al-joropo-de-guarico-y-zulia-avanza-invicto-en-busca-de-la-semifinal\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/digital58.com.ve\/site\/2023\/08\/24\/voleibol-la-gaita-silencio-al-joropo-de-guarico-y-zulia-avanza-invicto-en-busca-de-la-semifinal\/","url":"https:\/\/digital58.com.ve\/site\/2023\/08\/24\/voleibol-la-gaita-silencio-al-joropo-de-guarico-y-zulia-avanza-invicto-en-busca-de-la-semifinal\/","name":"#Voleibol | La gaita silenci\u00f3 al joropo de Gu\u00e1rico y Zulia avanza invicto en busca de la semifinal","isPartOf":{"@id":"https:\/\/digital58.com.ve\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/digital58.com.ve\/site\/2023\/08\/24\/voleibol-la-gaita-silencio-al-joropo-de-guarico-y-zulia-avanza-invicto-en-busca-de-la-semifinal\/#primaryimage"},"image":{"@id":"https:\/\/digital58.com.ve\/site\/2023\/08\/24\/voleibol-la-gaita-silencio-al-joropo-de-guarico-y-zulia-avanza-invicto-en-busca-de-la-semifinal\/#primaryimage"},"thumbnailUrl":"https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2023\/08\/voleibol-zulia-3.jpg","datePublished":"2023-08-25T03:03:54+00:00","breadcrumb":{"@id":"https:\/\/digital58.com.ve\/site\/2023\/08\/24\/voleibol-la-gaita-silencio-al-joropo-de-guarico-y-zulia-avanza-invicto-en-busca-de-la-semifinal\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/digital58.com.ve\/site\/2023\/08\/24\/voleibol-la-gaita-silencio-al-joropo-de-guarico-y-zulia-avanza-invicto-en-busca-de-la-semifinal\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/digital58.com.ve\/site\/2023\/08\/24\/voleibol-la-gaita-silencio-al-joropo-de-guarico-y-zulia-avanza-invicto-en-busca-de-la-semifinal\/#primaryimage","url":"https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2023\/08\/voleibol-zulia-3.jpg","contentUrl":"https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2023\/08\/voleibol-zulia-3.jpg","width":800,"height":496},{"@type":"BreadcrumbList","@id":"https:\/\/digital58.com.ve\/site\/2023\/08\/24\/voleibol-la-gaita-silencio-al-joropo-de-guarico-y-zulia-avanza-invicto-en-busca-de-la-semifinal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/digital58.com.ve\/site\/"},{"@type":"ListItem","position":2,"name":"#Voleibol | La gaita silenci\u00f3 al joropo de Gu\u00e1rico y Zulia avanza invicto en busca de la semifinal"}]},{"@type":"WebSite","@id":"https:\/\/digital58.com.ve\/site\/#website","url":"https:\/\/digital58.com.ve\/site\/","name":"Noticias Digital58","description":"Portal de Noticias \u00a1Periodismo web de verdad! Lanzamiento web 22.11.2005 \/ Maracaibo, Venezuela","publisher":{"@id":"https:\/\/digital58.com.ve\/site\/#\/schema\/person\/64d1c2e4d0d4fd1b849980c4331c2951"},"alternateName":"ND58","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/digital58.com.ve\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/digital58.com.ve\/site\/#\/schema\/person\/64d1c2e4d0d4fd1b849980c4331c2951","name":"Villasmil Henry","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/bb0c4a2fcb7970138239f7e404ea75757b1b507b28b5ce4c53fbd62d797c5a7c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bb0c4a2fcb7970138239f7e404ea75757b1b507b28b5ce4c53fbd62d797c5a7c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bb0c4a2fcb7970138239f7e404ea75757b1b507b28b5ce4c53fbd62d797c5a7c?s=96&d=mm&r=g","caption":"Villasmil Henry"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/bb0c4a2fcb7970138239f7e404ea75757b1b507b28b5ce4c53fbd62d797c5a7c?s=96&d=mm&r=g"},"sameAs":["http:\/\/www.henryvillasmil.com.ve","https:\/\/www.instagram.com\/villasmilhfoto\/","https:\/\/x.com\/https:\/\/twitter.com\/villasmilhfoto"],"url":"https:\/\/digital58.com.ve\/site\/author\/droopy_68\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2023\/08\/voleibol-zulia-3.jpg",800,496,false],"thumbnail":["https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2023\/08\/voleibol-zulia-3-150x150.jpg",150,150,true],"medium":["https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2023\/08\/voleibol-zulia-3-300x186.jpg",300,186,true],"medium_large":["https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2023\/08\/voleibol-zulia-3-768x476.jpg",768,476,true],"large":["https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2023\/08\/voleibol-zulia-3.jpg",800,496,false],"1536x1536":["https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2023\/08\/voleibol-zulia-3.jpg",800,496,false],"2048x2048":["https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2023\/08\/voleibol-zulia-3.jpg",800,496,false],"colormag-highlighted-post":["https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2023\/08\/voleibol-zulia-3-392x272.jpg",392,272,true],"colormag-featured-post-medium":["https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2023\/08\/voleibol-zulia-3-390x205.jpg",390,205,true],"colormag-featured-post-small":["https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2023\/08\/voleibol-zulia-3-130x90.jpg",130,90,true],"colormag-featured-image":["https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2023\/08\/voleibol-zulia-3-800x445.jpg",800,445,true],"colormag-default-news":["https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2023\/08\/voleibol-zulia-3-150x150.jpg",150,150,true],"colormag-featured-image-large":["https:\/\/digital58.com.ve\/site\/wp-content\/uploads\/2023\/08\/voleibol-zulia-3.jpg",800,496,false]},"uagb_author_info":{"display_name":"Villasmil Henry","author_link":"https:\/\/digital58.com.ve\/site\/author\/droopy_68\/"},"uagb_comment_info":0,"uagb_excerpt":"Los defensores de la casa se llevaron el trofeo alcald\u00eda de Maracaibo, que entreg\u00f3 el alcalde Rafael Ram\u00edrez Maracaibo, Zulia,","_links":{"self":[{"href":"https:\/\/digital58.com.ve\/site\/wp-json\/wp\/v2\/posts\/170019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digital58.com.ve\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/digital58.com.ve\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/digital58.com.ve\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/digital58.com.ve\/site\/wp-json\/wp\/v2\/comments?post=170019"}],"version-history":[{"count":1,"href":"https:\/\/digital58.com.ve\/site\/wp-json\/wp\/v2\/posts\/170019\/revisions"}],"predecessor-version":[{"id":170026,"href":"https:\/\/digital58.com.ve\/site\/wp-json\/wp\/v2\/posts\/170019\/revisions\/170026"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/digital58.com.ve\/site\/wp-json\/wp\/v2\/media\/170023"}],"wp:attachment":[{"href":"https:\/\/digital58.com.ve\/site\/wp-json\/wp\/v2\/media?parent=170019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/digital58.com.ve\/site\/wp-json\/wp\/v2\/categories?post=170019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/digital58.com.ve\/site\/wp-json\/wp\/v2\/tags?post=170019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}